{"id":7776,"date":"2024-11-26T19:51:01","date_gmt":"2024-11-26T19:51:01","guid":{"rendered":"https:\/\/fpisaofrancisco.inf.br\/?p=7776"},"modified":"2024-11-27T11:51:36","modified_gmt":"2024-11-27T11:51:36","slug":"sede-de-aprender-14fpial","status":"publish","type":"post","link":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/","title":{"rendered":"Sede de Aprender leva educa\u00e7\u00e3o ambiental, faz coleta de \u00e1gua para an\u00e1lise e avalia estrutura de escolas durante a FPI"},"content":{"rendered":"\n<p class=\"has-white-color has-accent-background-color has-text-color has-background has-link-color wp-elements-d20237f29b767e84bef3eb54b397c124\">Equipe j\u00e1 visitou 15 escolas em 5 munic\u00edpios, ouviu professores e t\u00e9cnicos e sensibilizou estudantes<\/p>\n\n\n\n<p>A manh\u00e3 dos alunos do 1\u00b0 ao 5\u00b0 ano da Escola Municipal de Educa\u00e7\u00e3o B\u00e1sica Maria J\u00falia Ferreira de Albuquerque, em Limoeiro de Anadia, foi de intera\u00e7\u00e3o, aprendizado sobre fauna nativa, uso racional dos recursos h\u00eddricos e sensibiliza\u00e7\u00e3o ambiental.<\/p>\n\n\n\n<p>Isso porque a unidade de ensino recebeu, nesta segunda-feira (25), a visita dos integrantes da equipe Sede de Aprender, da Fiscaliza\u00e7\u00e3o Preventiva Integrada da Bacia Hidrogr\u00e1fica do Rio S\u00e3o Francisco (FPI do Rio S\u00e3o Francisco).<\/p>\n\n\n\n<p>Na oportunidade, os alunos aprenderam com o Batalh\u00e3o de Pol\u00edcia Ambiental (BPA) e com o Instituto SOS Caatinga que n\u00e3o se pode ter em cativeiro aves e outras esp\u00e9cies nativas sem autoriza\u00e7\u00e3o dos \u00f3rg\u00e3os de fiscaliza\u00e7\u00e3o, bem como a import\u00e2ncia das aves, r\u00e9pteis e mam\u00edferos para o equil\u00edbrio dos ecossistemas. Eles tamb\u00e9m puderam ver de perto e tocar em animais que passaram pelo processo de taxidermia.<\/p>\n\n\n\n<p>Enquanto isso, em um ambiente reservado, os professores tiveram um momento com o Instituto para Preserva\u00e7\u00e3o da Mata Atl\u00e2ntica (IPMA) a respeito de temas de educa\u00e7\u00e3o ambiental, no qual foi incentivado o uso de fossa-jardim, dentre outras alternativas ambientais, como o pr\u00f3prio reuso da \u00e1gua na escola ou pela economia do recurso h\u00eddrico. O objetivo \u00e9 tornar permanentes as a\u00e7\u00f5es sobre sensibiliza\u00e7\u00e3o ambiental na institui\u00e7\u00e3o com o apoio dos professores em sala de aula e, para que isso aconte\u00e7a, \u00e9 importante conhecer para preservar.<\/p>\n\n\n\n<p>Paralelamente, auditores e t\u00e9cnicos do Tribunal de Contas do Estado (TCE) fiscalizaram a estrutura f\u00edsica da escola, do reservat\u00f3rio de \u00e1gua, das salas de aula, dos banheiros, da cozinha, a exist\u00eancia em quantidade e qualidade de merenda e o card\u00e1pio escolar.<\/p>\n\n\n\n<p>Todas essas a\u00e7\u00f5es ocorreram porque o Sede de Aprender, que nasceu fora do per\u00edodo da FPI e tem continuidade ap\u00f3s a a\u00e7\u00e3o concentrada de fiscaliza\u00e7\u00e3o, ultrapassou o objetivo inicial de fazer coleta de \u00e1gua para an\u00e1lise da qualidade.<\/p>\n\n\n\n<p>\u201cAgora, tamb\u00e9m promove palestras para conscientiza\u00e7\u00e3o ambiental dos alunos, desenvolve com os professores estrat\u00e9gias para a fixa\u00e7\u00e3o e continuidade das medidas em sala de aula, planeja a implanta\u00e7\u00e3o de fossa-jardim como uma das estrat\u00e9gias de uso, reuso e destina\u00e7\u00e3o da \u00e1gua, por meio do trabalho com ci\u00eancia, tecnologia e sustentabilidade e, por outro lado, tamb\u00e9m vistoria a infraestrutura predial como um todo\u201d, pontuou um dos coordenadores da equipe Sede de Aprender na FPI do Rio S\u00e3o Francisco, Meraldo Rocha.<\/p>\n\n\n\n<p>Nessa 14\u00aa edi\u00e7\u00e3o da FPI, a equipe do Sede de Aprender j\u00e1 esteve em 15 escolas de cinco munic\u00edpios. S\u00e3o eles: Limoeiro de Anadia, Junqueiro, Lagoa da Canoa, Feira Grande e Campo Grande.<\/p>\n\n\n\n<p>Na Escola Municipal de Educa\u00e7\u00e3o B\u00e1sica Maria J\u00falia Ferreira de Albuquerque, em Limoeiro de Anadia, t\u00e9cnicos do Instituto do Meio Ambiente de Alagoas (IMA) efetuaram a coleta da \u00e1gua para an\u00e1lise em laborat\u00f3rio, onde ser\u00e3o averiguados os par\u00e2metros f\u00edsico-qu\u00edmicos e microbiol\u00f3gicos.<\/p>\n\n\n\n<p>Como o projeto ser\u00e1 desenvolvido de forma duradoura na escola, t\u00e3o logo o laborat\u00f3rio libere os resultados da an\u00e1lise da \u00e1gua, eles ser\u00e3o informados pela coordena\u00e7\u00e3o geral da FPI do Rio S\u00e3o Francisco aos gestores municipais.<\/p>\n\n\n\n<p>Comp\u00f5em a equipe Sede de Aprender na FPI do Rio S\u00e3o Francisco o Instituto do Meio Ambiente de Alagoas (IMA), o Batalh\u00e3o de Pol\u00edcia Ambiental (BPA), o Instituto SOS Caatinga, o Instituto para Preserva\u00e7\u00e3o da Mata Atl\u00e2ntica (IPMA), o Tribunal de Contas do Estado de Alagoas (TCE) e o Minist\u00e9rio P\u00fablico de Alagoas (MPAL).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>A FPI do Rio S\u00e3o Francisco<\/strong><\/h3>\n\n\n\n<p>A FPI tem o objetivo de melhorar a qualidade ambiental da Bacia Hidrogr\u00e1fica do Rio S\u00e3o Francisco e a qualidade de vida dos seus povos. Os trabalhos acontecem de modo cont\u00ednuo e permanente. Para isso, realizam-se o diagn\u00f3stico dos danos ambientais e a ado\u00e7\u00e3o de provid\u00eancias administrativas, c\u00edveis e criminais com a indu\u00e7\u00e3o de pol\u00edticas p\u00fablicas.<\/p>\n\n\n\n<p>Como programa, a FPI \u00e9 estruturada em tr\u00eas fases: planejamento, campo e desdobramentos. A fase de desdobramento compreende o acompanhamento e monitoramento dos diagn\u00f3sticos realizados e a atua\u00e7\u00e3o de repercuss\u00f5es de medidas administrativas pelos \u00f3rg\u00e3os envolvidos, c\u00edveis e\/ou criminais e pelo Minist\u00e9rio P\u00fablico competente.<\/p>\n\n\n\n<p>Tamb\u00e9m \u00e9 na fase de desdobramentos que o poder p\u00fablico e a sociedade civil organizada contribuem na regulariza\u00e7\u00e3o dos empreendimentos, repara\u00e7\u00e3o de danos detectados e efetiva\u00e7\u00e3o das medidas de prote\u00e7\u00e3o necess\u00e1rias.<\/p>\n\n\n\n<p>Participam da 14\u00aa etapa da Fiscaliza\u00e7\u00e3o Preventiva Integrada a&nbsp;<a href=\"https:\/\/www.defesaagropecuaria.al.gov.br\/\">Ag\u00eancia de Defesa e Inspe\u00e7\u00e3o Agropecu\u00e1ria de Alagoas (Adeal),<\/a>&nbsp;<a href=\"https:\/\/alagoasdigital.al.gov.br\/unidade-de-atendimento\/814\">Batalh\u00e3o de Pol\u00edcia Ambiental da Pol\u00edcia Militar do Estado de Alagoas (BPA\/PMAL),<\/a>&nbsp;<a href=\"https:\/\/cbhsaofrancisco.org.br\/\">Comit\u00ea da Bacia Hidrogr\u00e1fica do Rio Francisco (CBHSF),<\/a><a href=\"https:\/\/www.crea-al.org.br\/\">&nbsp;Conselho Regional de Engenharia e Agronomia de Alagoas (Crea\/AL<\/a>),&nbsp;<a href=\"https:\/\/www.crmv-al.org.br\/\">Conselho Regional de Medicina Veterin\u00e1ria de Alagoas (CRMV\/AL),<\/a>&nbsp;<a href=\"https:\/\/www.crt03.gov.br\/\">Conselho Regional dos T\u00e9cnicos Industriais da 3\u00aa Regi\u00e3o (CRT-3)<\/a>,&nbsp;<a href=\"https:\/\/institutohori.org.br\/\">Instituto Hori,<\/a>&nbsp;<a href=\"https:\/\/www2.ima.al.gov.br\/\">Instituto do Meio Ambiente de Alagoas (IMA\/AL)<\/a>,&nbsp;<a href=\"https:\/\/ipma.org.br\/\">Instituto Para Preserva\u00e7\u00e3o da Mata Atl\u00e2ntica (IPMA)<\/a>,&nbsp;<a href=\"https:\/\/www.marinha.mil.br\/\">Marinha do Brasil<\/a>,&nbsp;<a href=\"https:\/\/www.mpal.mp.br\/\">Minist\u00e9rio P\u00fablico do Estado de Alagoas (MPE)<\/a>,&nbsp;<a href=\"https:\/\/www.mpf.mp.br\/al\/\">Minist\u00e9rio P\u00fablico Federal em Alagoas (MPF)<\/a>,&nbsp;<a href=\"https:\/\/www.prt19.mpt.mp.br\/\">Minist\u00e9rio P\u00fablico do Trabalho em Alagoas (MPT)<\/a>,&nbsp;<a href=\"https:\/\/www.gov.br\/pf\/pt-br\">Pol\u00edcia Federal (PF),<\/a>&nbsp;<a href=\"https:\/\/www.gov.br\/prf\/pt-br\">Pol\u00edcia Rodovi\u00e1ria Federal (PRF<\/a>),&nbsp;<a href=\"http:\/\/www.instagram.com\/redemulheresnct\">Rede Mulheres de Comunidades Tradicionais (RMCT)<\/a>,&nbsp;<a href=\"https:\/\/semarh.al.gov.br\/\">Secretaria de Estado do Meio Ambiente e Recursos H\u00eddricos (SEMARH)<\/a>,&nbsp;<a href=\"https:\/\/mulheredireitoshumanos.al.gov.br\/\">Secretaria de Estado da Mulher e dos Direitos Humanos (SEMUDH)<\/a>,&nbsp;<a href=\"https:\/\/www.saude.al.gov.br\/\">Secretaria de Estado da Sa\u00fade (Sesau)<\/a>,&nbsp;<a href=\"https:\/\/institutososcaatinga.com.br\/site\/\">SOS Caatinga<\/a>,&nbsp;<a href=\"https:\/\/www.tceal.tc.br\/\">Tribunal de Contas do Estado de Alagoas (TCE\/AL),<\/a>&nbsp;<a href=\"https:\/\/www.tre-al.jus.br\/\">Tribunal Regional Eleitoral de Alagoas (TRE\/AL)&nbsp;<\/a>e<a href=\"https:\/\/uneal.edu.br\/institucional\/a-uneal\">&nbsp;Universidade Estadual de Alagoas (Uneal).<\/a><\/p>\n\n\n\n<p>A FPI do Rio S\u00e3o Francisco em Alagoas \u00e9 coordenada pelo CBHSF, MPAL, MPF e BPA\/PMAL, que desenvolvem os trabalhos de intelig\u00eancia, organiza\u00e7\u00e3o e divulga\u00e7\u00e3o das atividades e resultados para a popula\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Leia tamb\u00e9m<\/strong><\/h3>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/macaco-prego-galego\/\">Amea\u00e7ado de extin\u00e7\u00e3o, Macaco-prego-galego \u00e9 resgatado pela FPI<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/kariri-xoco-etnozoneamento\/\">Kariri-Xoc\u00f3: etnozoneamento reivindicado ganhar\u00e1 ajuda da FPI<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/casas-de-farinha-inspecionadas\/\">FPI AL inspeciona casas de farinha em Junqueiro e orienta maior produtor da regi\u00e3o<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/25\/piracema\/\">FPI orienta pescadores em Pia\u00e7abu\u00e7u sobre per\u00edodo de defeso no Velho Chico<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/24\/granjas-clandestinas-sao-orientadas-pela-fpi\/\">Granjas clandestinas s\u00e3o orientadas pela FPI<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/24\/passaros-resgatados-voltam-para-casa\/\">No cora\u00e7\u00e3o da Caatinga, p\u00e1ssaros resgatados voltam para casa<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/23\/10-anos-fpial\/\">10 anos: FPI encerra 1a semana de mais uma etapa; Programa \u00e9 finalista do Innovare<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/23\/abate-clandestino-flagrado\/\">FPI flagra abate clandestino e evita o adoecimento da popula\u00e7\u00e3o em Penedo<\/a><br><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/22\/esgoto-contamina-rio-sao-francisco\/\">Esgoto contamina Rio S\u00e3o Francisco e amea\u00e7a a popula\u00e7\u00e3o de Olho d\u00b4\u00c1gua Grande<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/22\/comunidade-indigena-pankaraus-luzia\/\">Comunidade Ind\u00edgena Luzia da etnia Pankararu foi visitada<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/22\/lixao-flagrado-em-feira-grande\/\">FPI flagra lix\u00e3o, interdita \u00e1rea e multa a Prefeitura de Feira Grande em R$ 50 mil<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/21\/comunidades-indigenas-recebem-agua-sem-tratamento\/\">Comunidades ind\u00edgenas recebem \u00e1gua sem tratamento e Prefeitura \u00e9 notificada durante a\u00e7\u00e3o da FPI<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/21\/dialogo-com-ciganos\/\">FPI avan\u00e7a em di\u00e1logo com ciganos para inclus\u00e3o social em Penedo\/AL<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/21\/areas-desmatadas-embargadas-equivalem-a-419-campos-de-futebol\/\">FPI do Rio S\u00e3o Francisco embarga \u00e1reas desmatadas que equivalem a 419 campos de futebol<\/a><br><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/21\/barco-escola-promove-inclusao-e-educacao-ambiental\/\">No Dia da Consci\u00eancia Negra, barco-escola promove inclus\u00e3o e educa\u00e7\u00e3o ambiental<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/21\/pixaim-resiste\/\">Entre o rio e as dunas, Pixaim resiste: uma hist\u00f3ria de luta e ancestralidade<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/21\/aves-ganham-liberdade-no-dia-da-consciencia-negra\/\">De volta \u00e0 natureza: aves ganham liberdade no dia da Consci\u00eancia Negra<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/19\/quilombolas-do-oiteiro-e-tabuleiro-dos-negros\/\">FPI visita comunidades quilombolas do Oiteiro e Tabuleiro dos Negros<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/19\/agua-sem-tratamento-adequado-distribuida-para-comunidades-ribeirinhas\/\">FPI constata distribui\u00e7\u00e3o de \u00e1gua sem tratamento adequado a comunidades ribeirinhas<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/19\/criatorio-de-camaroes-tem-prazo-para-adequar-as-normas-ambientais\/\">Criat\u00f3rio de camar\u00f5es tem prazo de 30 dias para adequa\u00e7\u00e3o \u00e0s normas ambientais<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/19\/fpi-notifica-sete-embarcacoes\/\">FPI do Rio S\u00e3o Francisco notifica sete embarca\u00e7\u00f5es por infra\u00e7\u00f5es navais<\/a><\/p>\n\n\n\n<p><a href=\"http:\/\/xn--fpi%20flagra%20abate%20irregular%20de%20sunos%20em%20casa%20de%20farinha%20no%20agreste%20alagoano-s3i\/\">FPI flagra abate irregular de su\u00ednos em casa de farinha no Agreste alagoano<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/19\/crimes-ambientais-sao-flagrados-em-junqueiro\/\">Crimes ambientais s\u00e3o flagrados em Junqueiro pela FPI do Rio S\u00e3o Francisco<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/19\/fpi-resgata-34-aves\/\">FPI resgata 34 aves silvestres em Arapiraca<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/19\/fpi-interdita-790-litros-de-agrotoxicos\/\">FPI interdita 790 litros de agrot\u00f3xicos em com\u00e9rcio irregular<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/18\/14a-etapa-fpial_inicia\/\">FPI do Rio S\u00e3o Francisco d\u00e1 in\u00edcio \u00e0 14\u00aa etapa em Alagoas com foco em munic\u00edpios do Agreste e Sert\u00e3o<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Equipe j\u00e1 visitou 15 escolas em 5 munic\u00edpios, ouviu professores e t\u00e9cnicos e sensibilizou estudantes<\/p>\n","protected":false},"author":7,"featured_media":7777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[189],"tags":[220],"class_list":["post-7776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-14a-etapa-fpi-al","tag-14fpialagoas-riosaofrancisco-velhochico-defesadomeioambiente-povosdovelhochico-somostodoscarrancas-10anosfpial-cbhsf-sededeaprender-educacaoambiental","category-189","description-off"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Equipe j\u00e1 visitou 15 escolas em 5 munic\u00edpios, ouviu professores e t\u00e9cnicos e sensibilizou estudantes\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Rafael Barreto\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"fpisaofrancisco - Programa Fiscaliza\u00e7\u00e3o Preventiva Integrada do S\u00e2o Francisco\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sede de Aprender leva educa\u00e7\u00e3o ambiental e coleta de \u00e1gua\" \/>\n\t\t<meta property=\"og:description\" content=\"Equipe j\u00e1 visitou 15 escolas em 5 munic\u00edpios, ouviu professores e t\u00e9cnicos e sensibilizou estudantes\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-11-26T19:51:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-11-27T11:51:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sede de Aprender leva educa\u00e7\u00e3o ambiental e coleta de \u00e1gua\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Equipe j\u00e1 visitou 15 escolas em 5 munic\u00edpios, ouviu professores e t\u00e9cnicos e sensibilizou estudantes\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/11\\\/26\\\/sede-de-aprender-14fpial\\\/#blogposting\",\"name\":\"Sede de Aprender leva educa\\u00e7\\u00e3o ambiental e coleta de \\u00e1gua\",\"headline\":\"Sede de Aprender leva educa\\u00e7\\u00e3o ambiental, faz coleta de \\u00e1gua para an\\u00e1lise e avalia estrutura de escolas durante a FPI\",\"author\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/author\\\/rafael-barreto\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-26-at-18.30.57.jpeg\",\"width\":1280,\"height\":720,\"caption\":\"Cr\\u00e9dito comunica\\u00e7\\u00e3o FPI AL\"},\"datePublished\":\"2024-11-26T19:51:01+00:00\",\"dateModified\":\"2024-11-27T11:51:36+00:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/11\\\/26\\\/sede-de-aprender-14fpial\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/11\\\/26\\\/sede-de-aprender-14fpial\\\/#webpage\"},\"articleSection\":\"14\\u00aa Etapa FPI AL, #14FPIAlagoas #RioS\\u00e3oFrancisco #VelhoChico #DefesaDoMeioAmbiente #PovosDoVelhoChico #SomosTodosCarrancas #10AnosFPIAL #CBHSF #SedeDeAprender #EducacaoAmbiental\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/11\\\/26\\\/sede-de-aprender-14fpial\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpisaofrancisco.inf.br\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/category\\\/noticias-alagoas\\\/#listItem\",\"name\":\"Not\\u00edcias Alagoas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/category\\\/noticias-alagoas\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Alagoas\",\"item\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/category\\\/noticias-alagoas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/category\\\/noticias-alagoas\\\/14a-etapa-fpi-al\\\/#listItem\",\"name\":\"14\\u00aa Etapa FPI AL\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/category\\\/noticias-alagoas\\\/14a-etapa-fpi-al\\\/#listItem\",\"position\":3,\"name\":\"14\\u00aa Etapa FPI AL\",\"item\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/category\\\/noticias-alagoas\\\/14a-etapa-fpi-al\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/11\\\/26\\\/sede-de-aprender-14fpial\\\/#listItem\",\"name\":\"Sede de Aprender leva educa\\u00e7\\u00e3o ambiental, faz coleta de \\u00e1gua para an\\u00e1lise e avalia estrutura de escolas durante a FPI\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/category\\\/noticias-alagoas\\\/#listItem\",\"name\":\"Not\\u00edcias Alagoas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/11\\\/26\\\/sede-de-aprender-14fpial\\\/#listItem\",\"position\":4,\"name\":\"Sede de Aprender leva educa\\u00e7\\u00e3o ambiental, faz coleta de \\u00e1gua para an\\u00e1lise e avalia estrutura de escolas durante a FPI\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/category\\\/noticias-alagoas\\\/14a-etapa-fpi-al\\\/#listItem\",\"name\":\"14\\u00aa Etapa FPI AL\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/#organization\",\"name\":\"fpisaofrancisco\",\"description\":\"Programa Fiscaliza\\u00e7\\u00e3o Preventiva Integrada do S\\u00e2o Francisco\",\"url\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/author\\\/rafael-barreto\\\/#author\",\"url\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/author\\\/rafael-barreto\\\/\",\"name\":\"Rafael Barreto\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/11\\\/26\\\/sede-de-aprender-14fpial\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99277a4c60cb8142d84efa1224f652a3e8bc46a396d8117156df28d469542e9b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Rafael Barreto\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/11\\\/26\\\/sede-de-aprender-14fpial\\\/#webpage\",\"url\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/11\\\/26\\\/sede-de-aprender-14fpial\\\/\",\"name\":\"Sede de Aprender leva educa\\u00e7\\u00e3o ambiental e coleta de \\u00e1gua\",\"description\":\"Equipe j\\u00e1 visitou 15 escolas em 5 munic\\u00edpios, ouviu professores e t\\u00e9cnicos e sensibilizou estudantes\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/11\\\/26\\\/sede-de-aprender-14fpial\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/author\\\/rafael-barreto\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/author\\\/rafael-barreto\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-26-at-18.30.57.jpeg\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/11\\\/26\\\/sede-de-aprender-14fpial\\\/#mainImage\",\"width\":1280,\"height\":720,\"caption\":\"Cr\\u00e9dito comunica\\u00e7\\u00e3o FPI AL\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/11\\\/26\\\/sede-de-aprender-14fpial\\\/#mainImage\"},\"datePublished\":\"2024-11-26T19:51:01+00:00\",\"dateModified\":\"2024-11-27T11:51:36+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/#website\",\"url\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/\",\"name\":\"fpisaofrancisco\",\"description\":\"Programa Fiscaliza\\u00e7\\u00e3o Preventiva Integrada do S\\u00e2o Francisco\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sede de Aprender leva educa\u00e7\u00e3o ambiental e coleta de \u00e1gua","description":"Equipe j\u00e1 visitou 15 escolas em 5 munic\u00edpios, ouviu professores e t\u00e9cnicos e sensibilizou estudantes","canonical_url":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/#blogposting","name":"Sede de Aprender leva educa\u00e7\u00e3o ambiental e coleta de \u00e1gua","headline":"Sede de Aprender leva educa\u00e7\u00e3o ambiental, faz coleta de \u00e1gua para an\u00e1lise e avalia estrutura de escolas durante a FPI","author":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/author\/rafael-barreto\/#author"},"publisher":{"@id":"https:\/\/fpisaofrancisco.inf.br\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/fpisaofrancisco.inf.br\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-26-at-18.30.57.jpeg","width":1280,"height":720,"caption":"Cr\u00e9dito comunica\u00e7\u00e3o FPI AL"},"datePublished":"2024-11-26T19:51:01+00:00","dateModified":"2024-11-27T11:51:36+00:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/#webpage"},"isPartOf":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/#webpage"},"articleSection":"14\u00aa Etapa FPI AL, #14FPIAlagoas #RioS\u00e3oFrancisco #VelhoChico #DefesaDoMeioAmbiente #PovosDoVelhoChico #SomosTodosCarrancas #10AnosFPIAL #CBHSF #SedeDeAprender #EducacaoAmbiental"},{"@type":"BreadcrumbList","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br#listItem","position":1,"name":"Home","item":"https:\/\/fpisaofrancisco.inf.br","nextItem":{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/noticias-alagoas\/#listItem","name":"Not\u00edcias Alagoas"}},{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/noticias-alagoas\/#listItem","position":2,"name":"Not\u00edcias Alagoas","item":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/noticias-alagoas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/noticias-alagoas\/14a-etapa-fpi-al\/#listItem","name":"14\u00aa Etapa FPI AL"},"previousItem":{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/noticias-alagoas\/14a-etapa-fpi-al\/#listItem","position":3,"name":"14\u00aa Etapa FPI AL","item":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/noticias-alagoas\/14a-etapa-fpi-al\/","nextItem":{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/#listItem","name":"Sede de Aprender leva educa\u00e7\u00e3o ambiental, faz coleta de \u00e1gua para an\u00e1lise e avalia estrutura de escolas durante a FPI"},"previousItem":{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/noticias-alagoas\/#listItem","name":"Not\u00edcias Alagoas"}},{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/#listItem","position":4,"name":"Sede de Aprender leva educa\u00e7\u00e3o ambiental, faz coleta de \u00e1gua para an\u00e1lise e avalia estrutura de escolas durante a FPI","previousItem":{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/noticias-alagoas\/14a-etapa-fpi-al\/#listItem","name":"14\u00aa Etapa FPI AL"}}]},{"@type":"Organization","@id":"https:\/\/fpisaofrancisco.inf.br\/#organization","name":"fpisaofrancisco","description":"Programa Fiscaliza\u00e7\u00e3o Preventiva Integrada do S\u00e2o Francisco","url":"https:\/\/fpisaofrancisco.inf.br\/"},{"@type":"Person","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/author\/rafael-barreto\/#author","url":"https:\/\/fpisaofrancisco.inf.br\/index.php\/author\/rafael-barreto\/","name":"Rafael Barreto","image":{"@type":"ImageObject","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/99277a4c60cb8142d84efa1224f652a3e8bc46a396d8117156df28d469542e9b?s=96&d=mm&r=g","width":96,"height":96,"caption":"Rafael Barreto"}},{"@type":"WebPage","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/#webpage","url":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/","name":"Sede de Aprender leva educa\u00e7\u00e3o ambiental e coleta de \u00e1gua","description":"Equipe j\u00e1 visitou 15 escolas em 5 munic\u00edpios, ouviu professores e t\u00e9cnicos e sensibilizou estudantes","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/fpisaofrancisco.inf.br\/#website"},"breadcrumb":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/#breadcrumblist"},"author":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/author\/rafael-barreto\/#author"},"creator":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/author\/rafael-barreto\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/fpisaofrancisco.inf.br\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-26-at-18.30.57.jpeg","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/#mainImage","width":1280,"height":720,"caption":"Cr\u00e9dito comunica\u00e7\u00e3o FPI AL"},"primaryImageOfPage":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/#mainImage"},"datePublished":"2024-11-26T19:51:01+00:00","dateModified":"2024-11-27T11:51:36+00:00"},{"@type":"WebSite","@id":"https:\/\/fpisaofrancisco.inf.br\/#website","url":"https:\/\/fpisaofrancisco.inf.br\/","name":"fpisaofrancisco","description":"Programa Fiscaliza\u00e7\u00e3o Preventiva Integrada do S\u00e2o Francisco","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/fpisaofrancisco.inf.br\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"fpisaofrancisco - Programa Fiscaliza\u00e7\u00e3o Preventiva Integrada do S\u00e2o Francisco","og:type":"article","og:title":"Sede de Aprender leva educa\u00e7\u00e3o ambiental e coleta de \u00e1gua","og:description":"Equipe j\u00e1 visitou 15 escolas em 5 munic\u00edpios, ouviu professores e t\u00e9cnicos e sensibilizou estudantes","og:url":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/","article:published_time":"2024-11-26T19:51:01+00:00","article:modified_time":"2024-11-27T11:51:36+00:00","twitter:card":"summary_large_image","twitter:title":"Sede de Aprender leva educa\u00e7\u00e3o ambiental e coleta de \u00e1gua","twitter:description":"Equipe j\u00e1 visitou 15 escolas em 5 munic\u00edpios, ouviu professores e t\u00e9cnicos e sensibilizou estudantes"},"aioseo_meta_data":{"post_id":"7776","title":"Sede de Aprender leva educa\u00e7\u00e3o ambiental e coleta de \u00e1gua","description":"Equipe j\u00e1 visitou 15 escolas em 5 munic\u00edpios, ouviu professores e t\u00e9cnicos e sensibilizou estudantes","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-11-27 11:51:04","updated":"2025-06-04 13:44:17","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/fpisaofrancisco.inf.br\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/noticias-alagoas\/\" title=\"Not\u00edcias Alagoas\">Not\u00edcias Alagoas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/noticias-alagoas\/14a-etapa-fpi-al\/\" title=\"14\u00aa Etapa FPI AL\">14\u00aa Etapa FPI AL<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSede de Aprender leva educa\u00e7\u00e3o ambiental, faz coleta de \u00e1gua para an\u00e1lise e avalia estrutura de escolas durante a FPI\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/fpisaofrancisco.inf.br"},{"label":"Not\u00edcias Alagoas","link":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/noticias-alagoas\/"},{"label":"14\u00aa Etapa FPI AL","link":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/noticias-alagoas\/14a-etapa-fpi-al\/"},{"label":"Sede de Aprender leva educa\u00e7\u00e3o ambiental, faz coleta de \u00e1gua para an\u00e1lise e avalia estrutura de escolas durante a FPI","link":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/11\/26\/sede-de-aprender-14fpial\/"}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/fpisaofrancisco.inf.br\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-26-at-18.30.57.jpeg","_links":{"self":[{"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/posts\/7776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/comments?post=7776"}],"version-history":[{"count":1,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/posts\/7776\/revisions"}],"predecessor-version":[{"id":7778,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/posts\/7776\/revisions\/7778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/media\/7777"}],"wp:attachment":[{"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/media?parent=7776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/categories?post=7776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/tags?post=7776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}