{"id":7119,"date":"2024-05-15T17:43:46","date_gmt":"2024-05-15T17:43:46","guid":{"rendered":"https:\/\/fpisaofrancisco.inf.br\/?p=7119"},"modified":"2024-05-15T17:47:13","modified_gmt":"2024-05-15T17:47:13","slug":"em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama","status":"publish","type":"post","link":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/","title":{"rendered":"Em um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama"},"content":{"rendered":"\n<p><em>A\u00e7\u00f5es de fiscaliza\u00e7\u00e3o tiveram in\u00edcio nesta ter\u00e7a-feira (14), no Oeste do estado<\/em><\/p>\n\n\n\n<p>A entrega volunt\u00e1ria de animais silvestres e a fiscaliza\u00e7\u00e3o de criadores irregulares resultaram no resgate de 82 aves silvestres neste primeiro dia de atividades da 49\u00aa etapa da Fiscaliza\u00e7\u00e3o Preventiva Integrada (FPI) do S\u00e3o Francisco, que acontece em 10 munic\u00edpios da regi\u00e3o oeste da Bahia. As a\u00e7\u00f5es foram realizadas pela equipe de Fauna, composta pelo Instituto do Meio Ambiente e Recursos H\u00eddricos (INEMA), Pol\u00edcia Rodovi\u00e1ria Federal (PRF), Conselho Regional de Medicina Veterin\u00e1ria (CRMV), Conselho Regional de Engenharia e Agronomia da Bahia (CREA-BA) e a ONG Animallia.<\/p>\n\n\n\n<p>Durante as inspe\u00e7\u00f5es, um criador irregular foi apresentado na Delegacia de Pol\u00edcia Civil, pela posse ilegal de uma cartucheira calibre 36 e por manter 26 aves silvestres em cativeiro de forma irregular.<\/p>\n\n\n\n<p>As principais esp\u00e9cies encontradas foram Cardeal do Nordeste, Sabi\u00e1, Can\u00e1rio-da-terra, Periquito da Caatinga, Papagaio, Azul\u00e3o, Bigodinho e Papa-capim.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"6468\" height=\"4312\" src=\"https:\/\/fpisaofrancisco.inf.br\/wp-content\/uploads\/2024\/05\/3T7A5524.jpg\" alt=\"\" class=\"wp-image-7120\"\/><\/figure>\n\n\n\n<p>Durante as incurs\u00f5es feitas, tanto na zona urbana quanto na rural, os agentes averiguaram a situa\u00e7\u00e3o dos criadores registrados no Sistema para Gest\u00e3o de Criadores de Passeriformes Silvestres Nativos do Estado da Bahia (Sispass). \u201cOs animais que eram mantidos em cativeiro de forma irregular e com suspeitas de maus-tratos, assim que constatadas as irregularidades os criadores foram autuados e os animais resgatados\u201d, ressaltou o t\u00e9cnico do Inema e coordenador de uma das equipes de Fauna da FPI, Frederico Coelho. Ele tamb\u00e9m destacou um comportamento bastante positivo da popula\u00e7\u00e3o: \u201cNotamos, nesta fase, uma ades\u00e3o significativa ao procedimento da entrega volunt\u00e1ria. As pessoas, ao avistarem os ve\u00edculos da opera\u00e7\u00e3o, est\u00e3o nos procurando para entregar as aves que mantinham em suas resid\u00eancias\u201d.<\/p>\n\n\n\n<p>Em paralelo \u00e0 fiscaliza\u00e7\u00e3o, tamb\u00e9m est\u00e1 sendo realizado um trabalho de educa\u00e7\u00e3o ambiental e sensibiliza\u00e7\u00e3o junto as comunidades. Segundo o agente da Pol\u00edcia Rodovi\u00e1ria Federal (PRF), Marcus Fran\u00e7a, uma equipe est\u00e1 empenhada para orientar a popula\u00e7\u00e3o com a realiza\u00e7\u00e3o, por exemplo, de palestras nas escolas da regi\u00e3o: \u201cOs agentes ambientais e policiais est\u00e3o percorrendo os munic\u00edpios para coibir as pr\u00e1ticas ilegais e ao mesmo tempo exercer atividades de cunho da educa\u00e7\u00e3o ambiental. A fiscaliza\u00e7\u00e3o exige um trabalho minucioso, desde o planejamento, com a defini\u00e7\u00e3o de estrat\u00e9gias de abordagem, de inspe\u00e7\u00e3o e atendimento \u00e0s den\u00fancias que possam ocorrer durante a FPI\u201d.&nbsp;<\/p>\n\n\n\n<p>Ainda de acordo com Fran\u00e7a, a equipe Fauna da FPI atua em tr\u00eas frentes, com fiscaliza\u00e7\u00e3o em campo dos criadores amadores cadastrados no SISPASS, verificando se est\u00e3o atendendo aos requisitos estabelecidos nas legisla\u00e7\u00f5es estadual e federal, assim como aqueles animais em situa\u00e7\u00e3o de cativeiro ilegal, ou seja, sem as devidas autoriza\u00e7\u00f5es e registros. \u201cEstamos preparados para analisar todas as condi\u00e7\u00f5es, desde documentais at\u00e9 as de ca\u00e7a e maus-tratos aos animais silvestres, de acordo com os artigos 29 e 32, respectivamente, da Lei Federal 9.605\/98\u201d.&nbsp;<\/p>\n\n\n\n<p>A retirada de animais silvestres, adultos ou filhotes, de seus habitats naturais ocasiona uma redu\u00e7\u00e3o significativa nas popula\u00e7\u00f5es de diversas esp\u00e9cies e no desempenho de seus pap\u00e9is ecol\u00f3gicos na natureza, como na dispers\u00e3o de sementes, reprodu\u00e7\u00e3o e preda\u00e7\u00e3o natural de insetos e outros animais, entre outros.<\/p>\n\n\n\n<p><strong>Um exemplo de amor e prote\u00e7\u00e3o aos p\u00e1ssaros silvestres<\/strong><\/p>\n\n\n\n<p>Dona Diva, moradora do povoado do Alecrim, munic\u00edpio de Paratinga, ao avistar a equipe da FPI fez quest\u00e3o de convidar a todos para conhecer o quintal de sua casa e mostrar que a melhor forma de apreciar o canto dos p\u00e1ssaros \u00e9 com eles livres na natureza. \u201cAqui \u00e9 tudo muito simples, mas tem uma coisa que eu adoro fazer que \u00e9 ouvir os passarinhos cantando soltos na natureza, comendo as frutas direto nos p\u00e9s de goiaba, pinha e manga. Os bichinhos vivem mais feliz livres, voando pra todos os cantos, ent\u00e3o n\u00f3s temos que trabalhar para n\u00f3s e os outros tamb\u00e9m pensem assim\u201d.<\/p>\n\n\n\n<p><strong>Prote\u00e7\u00e3o da Fauna Silvestre<\/strong><\/p>\n\n\n\n<p>Os animais resgatados, apreendidos e recebidos voluntariamente, s\u00e3o encaminhados para uma base provis\u00f3ria do Centro de Triagem de Animais Silvestres (CETAS), montada no Col\u00e9gio Estadual Marechal Castelo Branco, localizado na Rua Pedro Olimpio de Souza, no centro da cidade de Ibotirama.&nbsp; O cidad\u00e3o que deseja realizar a entrega volunt\u00e1ria de animais silvestres deve se dirigir ao Cetas, das 09h \u00e0s 12h e das 14h \u00e0s 16h. \u00c9 importante ressaltar que, no ato da entrega volunt\u00e1ria, o respons\u00e1vel n\u00e3o ser\u00e1 multado nem responsabilizado criminalmente.&nbsp;<\/p>\n\n\n\n<p>&nbsp;\u201cAqui na base os animais passam por um rigoroso processo de triagem, uma avalia\u00e7\u00e3o com o intuito de verificar as condi\u00e7\u00f5es de sa\u00fade e recebem todo o tratamento necess\u00e1rio para recupera\u00e7\u00e3o e posterior soltura no seu habitat natural. Os principais problemas verificados, neste primeiro dia, est\u00e3o relacionados ao manejo nutricional, que acaba por afetar o estado cl\u00ednico destes animais, outro avalia\u00e7\u00e3o feita \u00e9 a comportamental, se apresentam caracter\u00edsticas de longo tempo em cativeiro\u201d, explicou o veterin\u00e1rio da Coordena\u00e7\u00e3o de Gest\u00e3o de Fauna do Inema, Caio Vinicius.<\/p>\n\n\n\n<p>Neste espa\u00e7o, uma equipe multidisciplinar atua com dedica\u00e7\u00e3o exclusiva para garantir o tratamento adequado, o bem-estar desses animais e as condi\u00e7\u00f5es necess\u00e1rias para a soltura na natureza.<\/p>\n\n\n\n<p>Andreza Amaral, bi\u00f3loga da ONG Animallia e coordenadora da equipe Base Fauna da FPI, explicou como ocorrem as atividades no Cetas montado em Ibotirama. \u201cEnt\u00e3o, n\u00f3s dividimos a equipe, uma parte dela fica na triagem individual de cada animal, a gente pega na m\u00e3o, avalia o score corporal, se tem algum ferimento, se o comportamento dele est\u00e1 adequado para a soltura ou n\u00e3o e, a partir da\u00ed, realizamos a manuten\u00e7\u00e3o da alimenta\u00e7\u00e3o adequada, pois a maioria deles vem subnutrido ou gordo demais, ent\u00e3o fazemos o ajuste necess\u00e1rio na alimenta\u00e7\u00e3o para que eles possam ingressar nos programas de soltura adequados em \u00e1reas regulares\u201d, destacou.<\/p>\n\n\n\n<p><strong>FPI S\u00e3o Francisco<\/strong><br><\/p>\n\n\n\n<p>A coordena\u00e7\u00e3o-geral da FPI \u00e9 realizada pelos Minist\u00e9rios P\u00fablicos da Bahia (MPBA) e do Trabalho (MPT) com apoio do Comit\u00ea da Bacia Hidrogr\u00e1fica do Rio S\u00e3o Francisco (CBHSF) e a participa\u00e7\u00e3o de mais de 200 agentes de 53 \u00f3rg\u00e3os das esferas estadual e federal, al\u00e9m de organiza\u00e7\u00f5es da sociedade civil.&nbsp;<\/p>\n\n\n\n<p>As a\u00e7\u00f5es abrangem os munic\u00edpios de Ibotirama, Paratinga, Oliveira dos Brejinhos, Muqu\u00e9m do S\u00e3o Francisco, Brotas de Maca\u00fabas, Ipupiara, Morpar\u00e1, Barra, Mansid\u00e3o e Buritirama.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"6453\" height=\"4301\" data-id=\"7123\" src=\"https:\/\/fpisaofrancisco.inf.br\/wp-content\/uploads\/2024\/05\/3T7A5412.jpg\" alt=\"\" class=\"wp-image-7123\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"6549\" height=\"4366\" data-id=\"7122\" src=\"https:\/\/fpisaofrancisco.inf.br\/wp-content\/uploads\/2024\/05\/3T7A5506.jpg\" alt=\"\" class=\"wp-image-7122\"\/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A\u00e7\u00f5es de fiscaliza\u00e7\u00e3o tiveram in\u00edcio nesta ter\u00e7a-feira (14), no Oeste do estado A entrega volunt\u00e1ria de animais silvestres e a fiscaliza\u00e7\u00e3o de criadores irregulares resultaram no resgate de 82 aves silvestres neste primeiro dia de atividades da 49\u00aa etapa da Fiscaliza\u00e7\u00e3o Preventiva Integrada (FPI) do S\u00e3o Francisco, que acontece em 10 munic\u00edpios da regi\u00e3o oeste&hellip;<\/p>\n","protected":false},"author":4,"featured_media":7125,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,71],"tags":[170,161,163,169],"class_list":["post-7119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-noticias-bahia","tag-cbhsf-2","tag-fpiba","tag-meioambiente-2","tag-velhochico-2","category-1","category-71","description-off"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"A\u00e7\u00f5es de fiscaliza\u00e7\u00e3o tiveram in\u00edcio nesta ter\u00e7a-feira (14), no Oeste do estado A entrega volunt\u00e1ria de animais silvestres e a fiscaliza\u00e7\u00e3o de criadores irregulares resultaram no resgate de 82 aves silvestres neste primeiro dia de atividades da 49\u00aa etapa da Fiscaliza\u00e7\u00e3o Preventiva Integrada (FPI) do S\u00e3o Francisco, que acontece em 10 munic\u00edpios da regi\u00e3o oeste\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"assessor.imprensa01\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"fpisaofrancisco - Programa Fiscaliza\u00e7\u00e3o Preventiva Integrada do S\u00e2o Francisco\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Em um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama - fpisaofrancisco\" \/>\n\t\t<meta property=\"og:description\" content=\"A\u00e7\u00f5es de fiscaliza\u00e7\u00e3o tiveram in\u00edcio nesta ter\u00e7a-feira (14), no Oeste do estado A entrega volunt\u00e1ria de animais silvestres e a fiscaliza\u00e7\u00e3o de criadores irregulares resultaram no resgate de 82 aves silvestres neste primeiro dia de atividades da 49\u00aa etapa da Fiscaliza\u00e7\u00e3o Preventiva Integrada (FPI) do S\u00e3o Francisco, que acontece em 10 munic\u00edpios da regi\u00e3o oeste\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-05-15T17:43:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-05-15T17:47:13+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Em um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama - fpisaofrancisco\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A\u00e7\u00f5es de fiscaliza\u00e7\u00e3o tiveram in\u00edcio nesta ter\u00e7a-feira (14), no Oeste do estado A entrega volunt\u00e1ria de animais silvestres e a fiscaliza\u00e7\u00e3o de criadores irregulares resultaram no resgate de 82 aves silvestres neste primeiro dia de atividades da 49\u00aa etapa da Fiscaliza\u00e7\u00e3o Preventiva Integrada (FPI) do S\u00e3o Francisco, que acontece em 10 munic\u00edpios da regi\u00e3o oeste\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/05\\\/15\\\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\\\/#blogposting\",\"name\":\"Em um \\u00fanico dia, FPI resgatou 82 aves silvestres na regi\\u00e3o de Ibotirama - fpisaofrancisco\",\"headline\":\"Em um \\u00fanico dia, FPI resgatou 82 aves silvestres na regi\\u00e3o de Ibotirama\",\"author\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/author\\\/assessor-imprensa01\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/3T7A5397-1-1-1.jpg\",\"width\":6603,\"height\":4401},\"datePublished\":\"2024-05-15T17:43:46+00:00\",\"dateModified\":\"2024-05-15T17:47:13+00:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/05\\\/15\\\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/05\\\/15\\\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\\\/#webpage\"},\"articleSection\":\"Blog, Not\\u00edcias Bahia, #cbhsf, #FPIBA, #MeioAmbiente, #VelhoChico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/05\\\/15\\\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fpisaofrancisco.inf.br\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/05\\\/15\\\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\\\/#listItem\",\"name\":\"Em um \\u00fanico dia, FPI resgatou 82 aves silvestres na regi\\u00e3o de Ibotirama\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/05\\\/15\\\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\\\/#listItem\",\"position\":3,\"name\":\"Em um \\u00fanico dia, FPI resgatou 82 aves silvestres na regi\\u00e3o de Ibotirama\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/#organization\",\"name\":\"fpisaofrancisco\",\"description\":\"Programa Fiscaliza\\u00e7\\u00e3o Preventiva Integrada do S\\u00e2o Francisco\",\"url\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/author\\\/assessor-imprensa01\\\/#author\",\"url\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/author\\\/assessor-imprensa01\\\/\",\"name\":\"assessor.imprensa01\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/05\\\/15\\\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee1f98bf2dcb547bf4d5c6c089c77c24de60a8bfbf35a324153a3bb0b321a67d?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"assessor.imprensa01\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/05\\\/15\\\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\\\/#webpage\",\"url\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/05\\\/15\\\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\\\/\",\"name\":\"Em um \\u00fanico dia, FPI resgatou 82 aves silvestres na regi\\u00e3o de Ibotirama - fpisaofrancisco\",\"description\":\"A\\u00e7\\u00f5es de fiscaliza\\u00e7\\u00e3o tiveram in\\u00edcio nesta ter\\u00e7a-feira (14), no Oeste do estado A entrega volunt\\u00e1ria de animais silvestres e a fiscaliza\\u00e7\\u00e3o de criadores irregulares resultaram no resgate de 82 aves silvestres neste primeiro dia de atividades da 49\\u00aa etapa da Fiscaliza\\u00e7\\u00e3o Preventiva Integrada (FPI) do S\\u00e3o Francisco, que acontece em 10 munic\\u00edpios da regi\\u00e3o oeste\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/05\\\/15\\\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/author\\\/assessor-imprensa01\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/author\\\/assessor-imprensa01\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/3T7A5397-1-1-1.jpg\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/05\\\/15\\\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\\\/#mainImage\",\"width\":6603,\"height\":4401},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/index.php\\\/2024\\\/05\\\/15\\\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\\\/#mainImage\"},\"datePublished\":\"2024-05-15T17:43:46+00:00\",\"dateModified\":\"2024-05-15T17:47:13+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/#website\",\"url\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/\",\"name\":\"fpisaofrancisco\",\"description\":\"Programa Fiscaliza\\u00e7\\u00e3o Preventiva Integrada do S\\u00e2o Francisco\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/fpisaofrancisco.inf.br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Em um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama - fpisaofrancisco","description":"A\u00e7\u00f5es de fiscaliza\u00e7\u00e3o tiveram in\u00edcio nesta ter\u00e7a-feira (14), no Oeste do estado A entrega volunt\u00e1ria de animais silvestres e a fiscaliza\u00e7\u00e3o de criadores irregulares resultaram no resgate de 82 aves silvestres neste primeiro dia de atividades da 49\u00aa etapa da Fiscaliza\u00e7\u00e3o Preventiva Integrada (FPI) do S\u00e3o Francisco, que acontece em 10 munic\u00edpios da regi\u00e3o oeste","canonical_url":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/#blogposting","name":"Em um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama - fpisaofrancisco","headline":"Em um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama","author":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/author\/assessor-imprensa01\/#author"},"publisher":{"@id":"https:\/\/fpisaofrancisco.inf.br\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/fpisaofrancisco.inf.br\/wp-content\/uploads\/2024\/05\/3T7A5397-1-1-1.jpg","width":6603,"height":4401},"datePublished":"2024-05-15T17:43:46+00:00","dateModified":"2024-05-15T17:47:13+00:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/#webpage"},"isPartOf":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/#webpage"},"articleSection":"Blog, Not\u00edcias Bahia, #cbhsf, #FPIBA, #MeioAmbiente, #VelhoChico"},{"@type":"BreadcrumbList","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br#listItem","position":1,"name":"Home","item":"https:\/\/fpisaofrancisco.inf.br","nextItem":{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/#listItem","name":"Em um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama"},"previousItem":{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/#listItem","position":3,"name":"Em um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama","previousItem":{"@type":"ListItem","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/fpisaofrancisco.inf.br\/#organization","name":"fpisaofrancisco","description":"Programa Fiscaliza\u00e7\u00e3o Preventiva Integrada do S\u00e2o Francisco","url":"https:\/\/fpisaofrancisco.inf.br\/"},{"@type":"Person","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/author\/assessor-imprensa01\/#author","url":"https:\/\/fpisaofrancisco.inf.br\/index.php\/author\/assessor-imprensa01\/","name":"assessor.imprensa01","image":{"@type":"ImageObject","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/ee1f98bf2dcb547bf4d5c6c089c77c24de60a8bfbf35a324153a3bb0b321a67d?s=96&d=mm&r=g","width":96,"height":96,"caption":"assessor.imprensa01"}},{"@type":"WebPage","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/#webpage","url":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/","name":"Em um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama - fpisaofrancisco","description":"A\u00e7\u00f5es de fiscaliza\u00e7\u00e3o tiveram in\u00edcio nesta ter\u00e7a-feira (14), no Oeste do estado A entrega volunt\u00e1ria de animais silvestres e a fiscaliza\u00e7\u00e3o de criadores irregulares resultaram no resgate de 82 aves silvestres neste primeiro dia de atividades da 49\u00aa etapa da Fiscaliza\u00e7\u00e3o Preventiva Integrada (FPI) do S\u00e3o Francisco, que acontece em 10 munic\u00edpios da regi\u00e3o oeste","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/fpisaofrancisco.inf.br\/#website"},"breadcrumb":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/#breadcrumblist"},"author":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/author\/assessor-imprensa01\/#author"},"creator":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/author\/assessor-imprensa01\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/fpisaofrancisco.inf.br\/wp-content\/uploads\/2024\/05\/3T7A5397-1-1-1.jpg","@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/#mainImage","width":6603,"height":4401},"primaryImageOfPage":{"@id":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/#mainImage"},"datePublished":"2024-05-15T17:43:46+00:00","dateModified":"2024-05-15T17:47:13+00:00"},{"@type":"WebSite","@id":"https:\/\/fpisaofrancisco.inf.br\/#website","url":"https:\/\/fpisaofrancisco.inf.br\/","name":"fpisaofrancisco","description":"Programa Fiscaliza\u00e7\u00e3o Preventiva Integrada do S\u00e2o Francisco","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/fpisaofrancisco.inf.br\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"fpisaofrancisco - Programa Fiscaliza\u00e7\u00e3o Preventiva Integrada do S\u00e2o Francisco","og:type":"article","og:title":"Em um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama - fpisaofrancisco","og:description":"A\u00e7\u00f5es de fiscaliza\u00e7\u00e3o tiveram in\u00edcio nesta ter\u00e7a-feira (14), no Oeste do estado A entrega volunt\u00e1ria de animais silvestres e a fiscaliza\u00e7\u00e3o de criadores irregulares resultaram no resgate de 82 aves silvestres neste primeiro dia de atividades da 49\u00aa etapa da Fiscaliza\u00e7\u00e3o Preventiva Integrada (FPI) do S\u00e3o Francisco, que acontece em 10 munic\u00edpios da regi\u00e3o oeste","og:url":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/","article:published_time":"2024-05-15T17:43:46+00:00","article:modified_time":"2024-05-15T17:47:13+00:00","twitter:card":"summary_large_image","twitter:title":"Em um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama - fpisaofrancisco","twitter:description":"A\u00e7\u00f5es de fiscaliza\u00e7\u00e3o tiveram in\u00edcio nesta ter\u00e7a-feira (14), no Oeste do estado A entrega volunt\u00e1ria de animais silvestres e a fiscaliza\u00e7\u00e3o de criadores irregulares resultaram no resgate de 82 aves silvestres neste primeiro dia de atividades da 49\u00aa etapa da Fiscaliza\u00e7\u00e3o Preventiva Integrada (FPI) do S\u00e3o Francisco, que acontece em 10 munic\u00edpios da regi\u00e3o oeste"},"aioseo_meta_data":{"post_id":"7119","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-05-15 17:43:48","updated":"2025-06-04 13:12:05","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/fpisaofrancisco.inf.br\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEm um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/fpisaofrancisco.inf.br"},{"label":"Blog","link":"https:\/\/fpisaofrancisco.inf.br\/index.php\/category\/blog\/"},{"label":"Em um \u00fanico dia, FPI resgatou 82 aves silvestres na regi\u00e3o de Ibotirama","link":"https:\/\/fpisaofrancisco.inf.br\/index.php\/2024\/05\/15\/em-um-unico-dia-fpi-resgatou-82-aves-silvestres-na-regiao-de-ibotirama\/"}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/fpisaofrancisco.inf.br\/wp-content\/uploads\/2024\/05\/3T7A5397-1-1-1.jpg","_links":{"self":[{"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/posts\/7119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/comments?post=7119"}],"version-history":[{"count":1,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/posts\/7119\/revisions"}],"predecessor-version":[{"id":7124,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/posts\/7119\/revisions\/7124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/media\/7125"}],"wp:attachment":[{"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/media?parent=7119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/categories?post=7119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fpisaofrancisco.inf.br\/index.php\/wp-json\/wp\/v2\/tags?post=7119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}